{"id":1324,"date":"2020-06-09T11:16:53","date_gmt":"2020-06-09T09:16:53","guid":{"rendered":"http:\/\/cgr-international.bb-b.net\/surmoulage\/"},"modified":"2025-05-21T18:13:00","modified_gmt":"2025-05-21T16:13:00","slug":"surmoulage-assemblage","status":"publish","type":"page","link":"https:\/\/www.cgr-international.com\/fr\/mecatronique\/surmoulage-assemblage\/","title":{"rendered":"Surmoulage &#8211; Assemblage"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":6853,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1324","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Surmoulage et assemblage automatis\u00e9 - CGR<\/title>\n<meta name=\"description\" content=\"CGR propose le surmoulage de pi\u00e8ces et l\u2019assemblage automatis\u00e9. Voici nos solutions pour vos projets m\u00e9catroniques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cgr-international.com\/fr\/mecatronique\/surmoulage-assemblage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Surmoulage - Assemblage\" \/>\n<meta property=\"og:description\" content=\"CGR propose le surmoulage de pi\u00e8ces et l\u2019assemblage automatis\u00e9. Voici nos solutions pour vos projets m\u00e9catroniques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cgr-international.com\/fr\/mecatronique\/surmoulage-assemblage\/\" \/>\n<meta property=\"og:site_name\" content=\"CGR\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T16:13:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/mecatronique\\\/surmoulage-assemblage\\\/\",\"url\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/mecatronique\\\/surmoulage-assemblage\\\/\",\"name\":\"Surmoulage et assemblage automatis\u00e9 - CGR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/#website\"},\"datePublished\":\"2020-06-09T09:16:53+00:00\",\"dateModified\":\"2025-05-21T16:13:00+00:00\",\"description\":\"CGR propose le surmoulage de pi\u00e8ces et l\u2019assemblage automatis\u00e9. Voici nos solutions pour vos projets m\u00e9catroniques.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/mecatronique\\\/surmoulage-assemblage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/mecatronique\\\/surmoulage-assemblage\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/mecatronique\\\/surmoulage-assemblage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9catronique\",\"item\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/mechatronics\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Surmoulage &#8211; Assemblage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/\",\"name\":\"CGR\",\"description\":\"Form your world\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/#organization\",\"name\":\"CGR International SAS\",\"url\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cgr-international.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/CG_logo_5-1.png\",\"contentUrl\":\"https:\\\/\\\/www.cgr-international.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/CG_logo_5-1.png\",\"width\":2375,\"height\":1182,\"caption\":\"CGR International SAS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cgr-international.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Surmoulage et assemblage automatis\u00e9 - CGR","description":"CGR propose le surmoulage de pi\u00e8ces et l\u2019assemblage automatis\u00e9. Voici nos solutions pour vos projets m\u00e9catroniques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cgr-international.com\/fr\/mecatronique\/surmoulage-assemblage\/","og_locale":"fr_FR","og_type":"article","og_title":"Surmoulage - Assemblage","og_description":"CGR propose le surmoulage de pi\u00e8ces et l\u2019assemblage automatis\u00e9. Voici nos solutions pour vos projets m\u00e9catroniques.","og_url":"https:\/\/www.cgr-international.com\/fr\/mecatronique\/surmoulage-assemblage\/","og_site_name":"CGR","article_modified_time":"2025-05-21T16:13:00+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cgr-international.com\/fr\/mecatronique\/surmoulage-assemblage\/","url":"https:\/\/www.cgr-international.com\/fr\/mecatronique\/surmoulage-assemblage\/","name":"Surmoulage et assemblage automatis\u00e9 - CGR","isPartOf":{"@id":"https:\/\/www.cgr-international.com\/fr\/#website"},"datePublished":"2020-06-09T09:16:53+00:00","dateModified":"2025-05-21T16:13:00+00:00","description":"CGR propose le surmoulage de pi\u00e8ces et l\u2019assemblage automatis\u00e9. Voici nos solutions pour vos projets m\u00e9catroniques.","breadcrumb":{"@id":"https:\/\/www.cgr-international.com\/fr\/mecatronique\/surmoulage-assemblage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cgr-international.com\/fr\/mecatronique\/surmoulage-assemblage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cgr-international.com\/fr\/mecatronique\/surmoulage-assemblage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cgr-international.com\/fr\/"},{"@type":"ListItem","position":2,"name":"M\u00e9catronique","item":"https:\/\/www.cgr-international.com\/fr\/mechatronics\/"},{"@type":"ListItem","position":3,"name":"Surmoulage &#8211; Assemblage"}]},{"@type":"WebSite","@id":"https:\/\/www.cgr-international.com\/fr\/#website","url":"https:\/\/www.cgr-international.com\/fr\/","name":"CGR","description":"Form your world","publisher":{"@id":"https:\/\/www.cgr-international.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cgr-international.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cgr-international.com\/fr\/#organization","name":"CGR International SAS","url":"https:\/\/www.cgr-international.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cgr-international.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.cgr-international.com\/wp-content\/uploads\/2020\/02\/CG_logo_5-1.png","contentUrl":"https:\/\/www.cgr-international.com\/wp-content\/uploads\/2020\/02\/CG_logo_5-1.png","width":2375,"height":1182,"caption":"CGR International SAS"},"image":{"@id":"https:\/\/www.cgr-international.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.cgr-international.com\/fr\/wp-json\/wp\/v2\/pages\/1324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cgr-international.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cgr-international.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cgr-international.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cgr-international.com\/fr\/wp-json\/wp\/v2\/comments?post=1324"}],"version-history":[{"count":2,"href":"https:\/\/www.cgr-international.com\/fr\/wp-json\/wp\/v2\/pages\/1324\/revisions"}],"predecessor-version":[{"id":5750,"href":"https:\/\/www.cgr-international.com\/fr\/wp-json\/wp\/v2\/pages\/1324\/revisions\/5750"}],"up":[{"embeddable":true,"href":"https:\/\/www.cgr-international.com\/fr\/wp-json\/wp\/v2\/pages\/6853"}],"wp:attachment":[{"href":"https:\/\/www.cgr-international.com\/fr\/wp-json\/wp\/v2\/media?parent=1324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}